{"id":5620,"date":"2024-01-18T15:42:54","date_gmt":"2024-01-18T15:42:54","guid":{"rendered":"https:\/\/www.dekkenmachinery.com\/politique-en-matiere-de-cookies-ue\/"},"modified":"2024-01-18T15:42:54","modified_gmt":"2024-01-18T15:42:54","slug":"politique-en-matiere-de-cookies-ue","status":"publish","type":"page","link":"https:\/\/dekkenmachinery.com\/fr\/politique-en-matiere-de-cookies-ue\/","title":{"rendered":"Politique en mati\u00e8re de cookies (UE)"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Cette politique de cookies a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois le mars 5, 2025 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00c9conomique Europ\u00e9en et de la Suisse.<\/i><br><\/p><h2>1. Introduction<\/h2><p>Notre site web, <a href=\"https:\/\/dekkenmachinery.com\/fr\/\">https:\/\/dekkenmachinery.com\/fr\/<\/a> (ci-apr\u00e8s\u00a0: \u00ab\u00a0le site web\u00a0\u00bb) utilise des cookies et autres technologies li\u00e9es (par simplification, toutes ces technologies sont d\u00e9sign\u00e9es par le terme \u00ab\u00a0cookies\u00a0\u00bb). Des cookies sont \u00e9galement plac\u00e9s par des tierces parties que nous avons engag\u00e9es. Dans le document ci-dessous, nous vous informons de l\u2019utilisation des cookies sur notre site web.<\/p><h2>2. Que sont les cookies\u00a0?<\/h2><p>Un cookie est un petit fichier simple envoy\u00e9 avec les pages de ce site web et stock\u00e9 par votre navigateur sur le disque dur de votre ordinateur ou d\u2019un autre appareil. Les informations qui y sont stock\u00e9es peuvent \u00eatre renvoy\u00e9es \u00e0 nos serveurs ou aux serveurs des tierces parties concern\u00e9es lors d\u2019une visite ult\u00e9rieure.<\/p><h2>3. Que sont les scripts\u00a0?<\/h2><p>Un script est un \u00e9l\u00e9ment de code utilis\u00e9 pour que notre site web fonctionne correctement et de mani\u00e8re interactive. Ce code est ex\u00e9cut\u00e9 sur notre serveur ou sur votre appareil.<\/p><h2>4. Qu\u2019est-ce qu\u2019une balise invisible\u00a0?<\/h2><p>Une balise invisible (ou balise web) est un petit morceau de texte ou d\u2019image invisible sur un site web, utilis\u00e9 pour suivre le trafic sur un site web. Pour ce faire, diverses donn\u00e9es vous concernant sont stock\u00e9es \u00e0 l\u2019aide de balises invisibles.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Cookies techniques ou fonctionnels<\/p><p>Certains cookies assurent le fonctionnement correct de certaines parties du site web et la prise en compte de vos pr\u00e9f\u00e9rences en tant qu\u2019utilisateur. En pla\u00e7ant des cookies fonctionnels, nous vous facilitons la visite de notre site web. Ainsi, vous n\u2019avez pas besoin de saisir \u00e0 plusieurs reprises les m\u00eames informations lors de la visite de notre site web et, par exemple, les \u00e9l\u00e9ments restent dans votre panier jusqu\u2019\u00e0 votre paiement. Nous pouvons placer ces cookies sans votre consentement.<\/p><h2>6. Cookies plac\u00e9s<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Statistiques (anonymes)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service elementor<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Elementor pour la cr\u00e9ation de contenu.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques (anonymes)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">elementor<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les actions effectu\u00e9es par les utilisateurs sur le site web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WordPress pour le d\u00e9veloppement du site web.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les informations du navigateur<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 an<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences des utilisateurs<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences des utilisateurs<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Garder les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WPML pour la gestion des param\u00e8tres r\u00e9gionaux.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 jour<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les r\u00e9glages de langue<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Maps pour l\u2019affichage de cartes.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">d\u00e9claration de confidentialit\u00e9 Google Maps<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">aucune<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Demander l\u2019adresse IP de l\u2019utilisateur<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Complianz pour la gestion du consentement aux cookies.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.&nbsp;Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">d\u00e9claration de confidentialit\u00e9 Complianz<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker l\u2019ID de la politique de cookies accept\u00e9e<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9morise si la banni\u00e8re des cookies a \u00e9t\u00e9 refus\u00e9e<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_user_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">D\u00e9terminer quel bandeau cookie afficher<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_saved_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_saved_categories<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">3000 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google reCAPTCHA pour le blocage des ind\u00e9sirables.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google reCAPTCHA<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Offrir une protection contre le spam<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rc::c<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rc::b<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rc::a<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Polylang<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_polylang\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service polylang<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_polylang\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"polylang\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Polylang pour la gestion des param\u00e8tres r\u00e9gionaux.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">pll_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les r\u00e9glages de langue<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Divers<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_divers\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service divers<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_divers\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"divers\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Le partage des donn\u00e9es est en cours d\u2019enqu\u00eate<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:*:timezone_offset<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:dist:geo:country:ef2eeb5<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:events:summary:53e41dbb<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:dist:browser:82faade8<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:top:referrers:3bb8ac4e<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:*:KKBCache<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">debug<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:account_infos:13fc3816<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:top:pages:a3a3e6de<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:*:edata:stored:account_infos<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:*:dbv1<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_aa_main_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:dist:os:1673336<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:traffic:last_30_days:e97183d6<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_aa_last_tracker_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">afslogged<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">afssetuser<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">in-move<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpml-job-list-collapsed<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:account_infos:e780a4a0<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_61663165-6338-5563-b736-613533643535<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cfEmail<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">adobeCleanFontAdded<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AFSA_DBOARD:01000519:stored_request:account_infos:ba6452da<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">activetab<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentement<\/h2><p>Lorsque vous visitez notre site web pour la premi\u00e8re fois, nous vous montrerons une fen\u00eatre contextuelle avec une explication sur les cookies. D\u00e8s que vous cliquez sur \u00ab\u00a0Accept\u00a0\u00bb, vous consentez \u00e0 ce que nous utilisions tous les cookies et extensions comme d\u00e9crit dans la fen\u00eatre contextuelle et la pr\u00e9sente politiquede cookies. Vous pouvez d\u00e9sactiver l\u2019utilisation des cookies via votre navigateur, mais veuillez noter que notre site web pourrait ne plus fonctionner correctement.<\/p><p class=\"cmplz-subtitle\">7.1 G\u00e9rez vos r\u00e9glages de consentement<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Vous avez charg\u00e9 la politique de cookies sans le support de javascript.&nbsp;Sur AMP, vous pouvez utiliser l\u2019onglet de gestion du consentement en bas de la page.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activer\/d\u00e9sactiver et supprimer les cookies<\/h2><p>Vous pouvez utiliser votre navigateur internet pour supprimer automatiquement ou manuellement les cookies. Vous pouvez \u00e9galement sp\u00e9cifier que certains cookies ne peuvent pas \u00eatre plac\u00e9s. Une autre option consiste \u00e0 modifier les r\u00e9glages de votre navigateur Internet afin que vous receviez un message \u00e0 chaque fois qu\u2019un cookie est plac\u00e9. Pour plus d\u2019informations sur ces options, reportez-vous aux instructions de la section Aide de votre navigateur.<\/p><p>Veuillez noter que notre site web peut ne pas marcher correctement si tous les cookies sont d\u00e9sactiv\u00e9s. Si vous supprimez les cookies dans votre navigateur, ils seront de nouveau plac\u00e9s apr\u00e8s votre consentement lorsque vous revisiterez notre site web.<\/p><h2>9. Vos droits concernant les donn\u00e9es personnelles<\/h2><p>Vous avez les droits suivants concernant vos donn\u00e9es personnelles\u00a0:<\/p><ul>\n                    <li>Vous avez le droit de savoir pourquoi vos donn\u00e9es personnelles sont n\u00e9cessaires, ce qui leur arrivera et combien de temps elles seront conserv\u00e9es.<\/li>\n                    <li>Droit d\u2019acc\u00e8s\u00a0: vous avez le droit d\u2019acc\u00e9der \u00e0 vos donn\u00e9es personnelles que nous connaissons.<\/li>\n                    <li>Droit de rectification\u00a0: vous avez le droit \u00e0 tout moment de compl\u00e9ter, corriger, faire supprimer ou bloquer vos donn\u00e9es personnelles.<\/li>\n                    <li>Si vous nous donnez votre consentement pour le traitement de vos donn\u00e9es, vous avez le droit de r\u00e9voquer ce consentement et de faire supprimer vos donn\u00e9es personnelles.<\/li>\n                    <li>Droit de transf\u00e9rer vos donn\u00e9es\u00a0: vous avez le droit de demander toutes vos donn\u00e9es personnelles au responsable du traitement et de les transf\u00e9rer dans leur int\u00e9gralit\u00e9 \u00e0 un autre responsable du traitement.<\/li>\n                    <li>Droit d\u2019opposition\u00a0: vous pouvez vous opposer au traitement de vos donn\u00e9es. Nous obtemp\u00e9rerons, \u00e0 moins que certaines raisons ne justifient ce traitement.<\/li>\n                <\/ul><p>Pour exercer ces droits, veuillez nous contacter. Veuillez vous r\u00e9f\u00e9rer aux coordonn\u00e9es au bas de cette politique de cookies. Si vous avez une plainte concernant la fa\u00e7on dont nous traitons vos donn\u00e9es, nous aimerions en \u00eatre inform\u00e9s, mais vous avez \u00e9galement le droit de d\u00e9poser une plainte aupr\u00e8s de l\u2019autorit\u00e9 de contr\u00f4le (l\u2019autorit\u00e9 charg\u00e9e de la protection des donn\u00e9es).<\/p><h2>10. Coordonn\u00e9es<\/h2><p>Pour des questions et\/ou des commentaires sur notre politique de cookies et cette d\u00e9claration, veuillez nous contacter en utilisant les coordonn\u00e9es suivantes\u00a0:<\/p><p><span class=\"cmplz-contact-organisation\">Dekken SRL<\/span><br>\n                      <span class=\"cmplz-contact-address\">Euregiostrasse 1, 4700 Eupen, Belgium<\/span><br>\n                      <span class=\"cmplz-contact-country\">Belgique<\/span><br>\n                    Site web\u00a0: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/dekkenmachinery.com\/fr\/\">https:\/\/dekkenmachinery.com\/fr\/<\/a><\/span><br>\n                    E-mail\u00a0: <span class=\"cmplz-contact-email\">&#105;&#110;f&#111;&#064;&#100;&#101;&#107;&#107;&#101;nma&#099;&#104;&#105;nery.co&#109;<\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Phone number: +32 483 00 79 79<\/span><\/p><p>Cette politique de cookies a \u00e9t\u00e9 synchronis\u00e9e avec <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> le mai 7, 2026.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5620","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Politique en mati\u00e8re de cookies (UE) - Dekken Machinery<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique en mati\u00e8re de cookies (UE) - Dekken Machinery\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/\" \/>\n<meta property=\"og:site_name\" content=\"Dekken Machinery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/\",\"url\":\"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/\",\"name\":\"Politique en mati\u00e8re de cookies (UE) - Dekken Machinery\",\"isPartOf\":{\"@id\":\"https:\/\/dekkenmachinery.com\/#website\"},\"datePublished\":\"2024-01-18T15:42:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dekkenmachinery.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique en mati\u00e8re de cookies (UE)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dekkenmachinery.com\/#website\",\"url\":\"https:\/\/dekkenmachinery.com\/\",\"name\":\"Dekken Machinery\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dekkenmachinery.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique en mati\u00e8re de cookies (UE) - Dekken Machinery","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique en mati\u00e8re de cookies (UE) - Dekken Machinery","og_url":"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/","og_site_name":"Dekken Machinery","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/","url":"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/","name":"Politique en mati\u00e8re de cookies (UE) - Dekken Machinery","isPartOf":{"@id":"https:\/\/dekkenmachinery.com\/#website"},"datePublished":"2024-01-18T15:42:54+00:00","breadcrumb":{"@id":"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dekkenmachinery.com\/cookie-policy-eu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dekkenmachinery.com\/cookie-policy-eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dekkenmachinery.com\/"},{"@type":"ListItem","position":2,"name":"Politique en mati\u00e8re de cookies (UE)"}]},{"@type":"WebSite","@id":"https:\/\/dekkenmachinery.com\/#website","url":"https:\/\/dekkenmachinery.com\/","name":"Dekken Machinery","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dekkenmachinery.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/dekkenmachinery.com\/fr\/wp-json\/wp\/v2\/pages\/5620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dekkenmachinery.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dekkenmachinery.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dekkenmachinery.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dekkenmachinery.com\/fr\/wp-json\/wp\/v2\/comments?post=5620"}],"version-history":[{"count":0,"href":"https:\/\/dekkenmachinery.com\/fr\/wp-json\/wp\/v2\/pages\/5620\/revisions"}],"wp:attachment":[{"href":"https:\/\/dekkenmachinery.com\/fr\/wp-json\/wp\/v2\/media?parent=5620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}